{"id":6287,"date":"2025-10-07T18:07:38","date_gmt":"2025-10-07T21:07:38","guid":{"rendered":"https:\/\/fmgente.com.ar\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/"},"modified":"2025-10-07T18:07:38","modified_gmt":"2025-10-07T21:07:38","slug":"valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a","status":"publish","type":"post","link":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/","title":{"rendered":"Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d"},"content":{"rendered":"<p><strong>Valentina Cervantes<\/strong> se anim\u00f3 a abrir la puerta de uno de los espacios m\u00e1s misteriosos del mundo del f\u00fatbol: el grupo de WhatsApp que comparten las parejas de los jugadores de la <strong>Selecci\u00f3n argentina<\/strong>. En una charla en Resu en vivo, la pareja de <strong>Enzo Fern\u00e1ndez<\/strong> rompi\u00f3 el silencio sobre ese chat del que tanto se habl\u00f3 y lo defini\u00f3 con una frase simple pero reveladora: \u201cEs muy lindo\u201d.<\/p>\n<p>Queriendo dejar en claro que no existen internas ni diferentes facciones dentro del grupo de mujeres, <strong><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/valentina-cervantes-conto-el-secreto-mejor-guardado-de-enzo-fernandez-y-genero-revuelo\/\">Valentina<\/a><\/strong> explic\u00f3 que no existen ni diferencias, ni expulsiones ni conflictos como muchos a veces se pueden imaginar. <em>\u201cNo, ah\u00ed est\u00e1n todas\u201d<\/em>, asegur\u00f3, cuando le preguntaron si exist\u00eda realmente y si alguna vez hab\u00edan sacado a alguien.<\/p>\n<p>Luego <strong><a href=\"https:\/\/www.paparazzi.com.ar\/deportes\/valentina-cervantes-revelo-el-problema-que-enfrentan-con-enzo-fernandez-a-6-meses-de-reconciliarse\/\">Valentina<\/a><\/strong> fue mucho m\u00e1s all\u00e1, remarcando el hecho de que nunca decidieron expulsar a nadie del grupo a pesar de lo que pueda surgir interna o externamente: <em>\u201cNunca se saca a nadie. La que sale, sale porque quiere, pero nunca se sac\u00f3 a nadie. Suponete que se separa, sale sola la chica. Nadie echa a nadie. No, ser\u00eda horrible\u201d<\/em>.<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/videos\/exclusivo-marcelo-polino-hablo-como-nunca-de-su-vida-intima-y-conto-cuando-fue-la-ultima-vez-que-tuvo-sexo-con-una-mujer\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/IMG_5980.jpg.webp\" alt=\"\u00a1Exclusivo! Marcelo Polino habl\u00f3 como nunca de su vida \u00edntima y cont\u00f3 cu\u00e1ndo fue la \u00faltima vez que tuvo sexo con una mujer&nbsp;\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">\u00a1Exclusivo! Marcelo Polino habl\u00f3 como nunca de su vida \u00edntima y cont\u00f3 cu\u00e1ndo fue la \u00faltima vez que tuvo sexo con una mujer&nbsp;<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>De esta forma, <strong>la pareja de Enzo<\/strong> descart\u00f3 las supuestas guerras entre las parejas de los futbolistas. Seg\u00fan explic\u00f3, el grupo existe y funciona con naturalidad: se enciende en tiempos de competencia y se apaga en los meses m\u00e1s tranquilos. <em>\u201cAhora no se habla, pero m\u00e1s adelante s\u00ed se va a empezar a hablar\u201d<\/em>, cont\u00f3. Y agreg\u00f3: <em>\u201cNo, capaz en el a\u00f1o no, pero cuando vienen tipo Copa Am\u00e9rica, Mundial, ah\u00ed se habla un poco m\u00e1s\u201d<\/em>.<\/p>\n<h2 class=\"wp-block-heading\">LOS SECRETOS DEL GRUPO PRIVADO DE LAS MUJERES DE LA SELECCI\u00d3N ARGENTINA<\/h2>\n<p>En etapa de competencia cuando la <strong>Selecci\u00f3n<\/strong> vuelve a jugar, el chat se convierte en una verdadera herramienta de coordinaci\u00f3n. Las parejas organizan viajes, horarios, reencuentros y todo lo necesario para acompa\u00f1ar a los jugadores. <em>\u201cEs s\u00faper lindo. Salimos a comer juntas\u201d<\/em>, coment\u00f3 <strong>Valentina<\/strong> sobre el clima de camarader\u00eda que existe entre ellas.<\/p>\n<p>Pero otra de las preguntas que no pudo evitar la modelo fue: \u00bfest\u00e1 <strong>Tini Stoessel <\/strong>en el grupo? Todo esto recordando que la cantante pas\u00f3 por una separaci\u00f3n y reconciliaci\u00f3n con Rodrigo de Paul. Sin embargo, <strong><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/la-foto-de-pampita-disfrutando-la-noche-con-enzo-fernandez-y-valentina-cervantes-juntos\/\">Valentina<\/a><\/strong> se hizo la desentendida <em>\u201cAy, \u00bfsab\u00e9s que no s\u00e9? Tendr\u00eda que chequear, pero debe estar\u201d<\/em>. Y frente a la broma sobre si se sumar\u00eda <em>\u201ccuando se case\u201d<\/em>, r\u00e1pidamente aclar\u00f3: <em>\u201cNo hace falta que est\u00e9 casada, porque yo no estoy casada tampoco\u201d<\/em>.<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/valentina-cervantes-conto-el-secreto-mejor-guardado-de-enzo-fernandez-y-genero-revuelo\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/image-242.png.webp\" alt=\"Valentina Cervantes cont\u00f3 el secreto mejor guardado de Enzo Fern\u00e1ndez y gener\u00f3 revuelo\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">Valentina Cervantes cont\u00f3 el secreto mejor guardado de Enzo Fern\u00e1ndez y gener\u00f3 revuelo<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>Para cerrar, <strong>Cervantes<\/strong> se sincer\u00f3 por los v\u00ednculos que ha ido generando con las dem\u00e1s mujeres de la <strong>Selecci\u00f3n<\/strong>. <em>\u201cCon todas\u201d<\/em>, dijo sobre con qui\u00e9nes se lleva mejor. Aunque lo cierto es que record\u00f3 con cari\u00f1o a alguien muy especial que hoy ya no se encuentra en el grupo: <em>\u201cHe conocido a muchas, algunas que ya no est\u00e1n, como Jorgelina, la mujer de \u00c1ngel (Di Mar\u00eda), que me ayud\u00f3 un mont\u00f3n\u201d<\/em>.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"578\" height=\"576\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/valentina-cervantes-whatsapp-seleccion-1.png.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-446719\" \/><\/figure>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"578\" height=\"576\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/valentina-cervantes-whatsapp-seleccion-2.png.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-446720\" \/><\/figure>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"578\" height=\"576\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/valentina-cervantes-whatsapp-seleccion-3.png.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-446721\" \/><\/figure>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/deportes\/valentina-cervantes-revelo-el-problema-que-enfrentan-con-enzo-fernandez-a-6-meses-de-reconciliarse\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/06\/\u00bfArrepentida-La-inesperada-revelacion-de-Valentina-Cervantes-tras-perdonar-a-Enzo-Fernandez.jpg.webp\" alt=\"Valentina Cervantes revel\u00f3 el problema que enfrentan con Enzo Fern\u00e1ndez a 6 meses de reconciliarse\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">Valentina Cervantes revel\u00f3 el problema que enfrentan con Enzo Fern\u00e1ndez a 6 meses de reconciliarse<\/h5>\n<\/div>\n<p><\/a><\/div>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/la-foto-de-pampita-disfrutando-la-noche-con-enzo-fernandez-y-valentina-cervantes-juntos\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/08\/pampita-5.png.webp\" alt=\"La foto de Pampita disfrutando la noche con Enzo Fern\u00e1ndez y Valentina Cervantes juntos\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">La foto de Pampita disfrutando la noche con Enzo Fern\u00e1ndez y Valentina Cervantes juntos<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>The post <a href=\"https:\/\/www.paparazzi.com.ar\/teve\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/\">Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d<\/a> appeared first on <a href=\"https:\/\/www.paparazzi.com.ar\">Revista Paparazzi<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valentina Cervantes se anim\u00f3 a abrir la puerta de uno de los espacios m\u00e1s misteriosos<\/p>\n","protected":false},"author":0,"featured_media":6288,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-6287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d - Fm Gente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d - Fm Gente\" \/>\n<meta property=\"og:description\" content=\"Valentina Cervantes se anim\u00f3 a abrir la puerta de uno de los espacios m\u00e1s misteriosos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Fm Gente\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T21:07:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-11.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d\",\"datePublished\":\"2025-10-07T21:07:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/\"},\"wordCount\":635,\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980.jpg-11.webp\",\"articleSection\":[\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/\",\"name\":\"Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d - Fm Gente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980.jpg-11.webp\",\"datePublished\":\"2025-10-07T21:07:38+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980.jpg-11.webp\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980.jpg-11.webp\",\"width\":1900,\"height\":1425},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"name\":\"Fm Gente\",\"description\":\"- Jes\u00fas Mar\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\",\"name\":\"Fm Gente\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"width\":1782,\"height\":1782,\"caption\":\"Fm Gente\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d - Fm Gente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/","og_locale":"es_ES","og_type":"article","og_title":"Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d - Fm Gente","og_description":"Valentina Cervantes se anim\u00f3 a abrir la puerta de uno de los espacios m\u00e1s misteriosos","og_url":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/","og_site_name":"Fm Gente","article_published_time":"2025-10-07T21:07:38+00:00","og_image":[{"width":1900,"height":1425,"url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-11.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/#article","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/"},"author":{"name":"","@id":""},"headline":"Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d","datePublished":"2025-10-07T21:07:38+00:00","mainEntityOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/"},"wordCount":635,"publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-11.webp","articleSection":["DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/","url":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/","name":"Valentina Cervantes cont\u00f3 toda la verdad del chat de WhatsApp de las esposas de la Selecci\u00f3n: \u201cNo echamos a\u2026\u201d - Fm Gente","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/#primaryimage"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-11.webp","datePublished":"2025-10-07T21:07:38+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/valentina-cervantes-conto-toda-la-verdad-del-chat-de-whatsapp-de-las-esposas-de-la-seleccion-no-echamos-a\/#primaryimage","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-11.webp","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-11.webp","width":1900,"height":1425},{"@type":"WebSite","@id":"https:\/\/fmgente.com.ar\/web\/#website","url":"https:\/\/fmgente.com.ar\/web\/","name":"Fm Gente","description":"- Jes\u00fas Mar\u00eda","publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fmgente.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fmgente.com.ar\/web\/#organization","name":"Fm Gente","url":"https:\/\/fmgente.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","width":1782,"height":1782,"caption":"Fm Gente"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6287"}],"version-history":[{"count":0,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media\/6288"}],"wp:attachment":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}