{"id":6215,"date":"2025-10-06T21:05:08","date_gmt":"2025-10-07T00:05:08","guid":{"rendered":"https:\/\/fmgente.com.ar\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/"},"modified":"2025-10-06T21:05:08","modified_gmt":"2025-10-07T00:05:08","slug":"la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud","status":"publish","type":"post","link":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/","title":{"rendered":"La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud"},"content":{"rendered":"<p>Durante los \u00faltimos meses, la <strong>China Su\u00e1rez<\/strong> es noticia por una serie de decisiones respecto a su vida privada. Y esta vez, un gesto en redes sociales volvi\u00f3 a encender las alarmas sobre su v\u00ednculo con Pampita. Aunque siempre se habl\u00f3 de una guerra silenciosa tapada por los flashes y las poses bonitas, la cual muchos negaban, hablamos de una situaci\u00f3n que puede traer un esc\u00e1ndalo de fondo.<\/p>\n<p>Instalada desde hace semanas en Turqu\u00eda junto a Mauro Icardi como parte de una id\u00edlica historia de amor que protagoniza, la <strong>China<\/strong> sorprendi\u00f3 al dejar de seguir a <strong><a href=\"https:\/\/www.paparazzi.com.ar\/romances\/la-drastica-decision-de-vida-la-china-suarez-apostando-todo-a-su-amor-con-mauro-icardi\/\">Pampita<\/a><\/strong> en Instagram. Este particular detalle fue descubierto por Juariu, especialista en seguirle el rastro a los famosos en las plataformas virtuales, y r\u00e1pidamente se volvi\u00f3 un tema de conversaci\u00f3n.<\/p>\n<p>Este giro fue interpretado por muchos como una se\u00f1al de quiebre en la relaci\u00f3n cordial que ambas hab\u00edan logrado reconstruir con el paso del tiempo. Despu\u00e9s de haber protagonizado uno de los episodios m\u00e1s recordados de la far\u00e1ndula -con el esc\u00e1ndalo del Motorhome que incluy\u00f3 la palta y la manta de Nepal-, el v\u00ednculo entre la <strong><a href=\"https:\/\/www.paparazzi.com.ar\/romances\/el-ultimatum-de-zoe-bogach-por-su-romance-con-mauro-icardi-que-destrozo-a-la-china-suarez-tapa-su-infidelidad-y\/\">China<\/a><\/strong> y <strong>Pampita<\/strong> parec\u00eda ser amigable. Sin embargo, este<em> \u201cunfollow\u201d <\/em>gener\u00f3 una grieta.<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/videos\/exclusivo-marcelo-polino-hablo-como-nunca-de-su-vida-intima-y-conto-cuando-fue-la-ultima-vez-que-tuvo-sexo-con-una-mujer\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/IMG_5980.jpg.webp\" alt=\"\u00a1Exclusivo! Marcelo Polino habl\u00f3 como nunca de su vida \u00edntima y cont\u00f3 cu\u00e1ndo fue la \u00faltima vez que tuvo sexo con una mujer\u00a0\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">\u00a1Exclusivo! Marcelo Polino habl\u00f3 como nunca de su vida \u00edntima y cont\u00f3 cu\u00e1ndo fue la \u00faltima vez que tuvo sexo con una mujer\u00a0<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>Lo cierto es que este <em>\u201cunfollow\u201d <\/em>viene solo a trav\u00e9s de la <strong><a href=\"https:\/\/www.paparazzi.com.ar\/romances\/revelaron-la-verdad-detras-de-la-visita-de-mauro-icardi-al-psicologo-por-sus-hijas-es-mentira-que\/\">China<\/a><\/strong>, ya que seg\u00fan tambi\u00e9n indicaron, Pampita s\u00ed estar\u00eda a\u00fan <em>\u201csiguiendo\u201d <\/em>a la actriz. Todo esto se da en medio de los esc\u00e1ndalos que la ex Casi \u00c1ngeles viene protagonizando, con un cambio de vida absoluto desde que confirm\u00f3 su noviazgo con <strong>Mauro Icardi<\/strong> y decidi\u00f3 radicarse en Turqu\u00eda junto al futbolista.<\/p>\n<h2 class=\"wp-block-heading\">POR QU\u00c9 LA CHINA SU\u00c1REZ DEJ\u00d3 DE SEGUIR A PAMPITA EN SU INSTAGRAM<\/h2>\n<p>La vida de la <strong>China<\/strong> ha tenido fuertes cambios en los \u00faltimos meses. Recientemente compr\u00f3 una lujosa casa en Turqu\u00eda, donde planea instalarse junto al delantero rosarino, y tambi\u00e9n decidi\u00f3 desprenderse de una de sus propiedades en el barrio de Palermo. Un movimiento que muchos leen como el cierre de un ciclo y el comienzo de otro.<\/p>\n<p>En paralelo, sostiene un fuerte conflicto con <strong>Benjam\u00edn Vicu\u00f1a<\/strong> por sus dos hijos, como parte de una relaci\u00f3n que tambi\u00e9n se estanc\u00f3 durante los \u00faltimos meses. Ahora se suma esta distancia con <strong>Pampita<\/strong>, que recordemos en m\u00e1s de una ocasi\u00f3n sali\u00f3 a defender al actor chileno en medio de esta guerra fr\u00eda que tienen por los menores. \u00bfSer\u00e1 una represalia?<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/romances\/la-drastica-decision-de-vida-la-china-suarez-apostando-todo-a-su-amor-con-mauro-icardi\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/China-Suarez-Mauro-Icardi-1-1-359x226.jpg\" alt=\"La dr\u00e1stica decisi\u00f3n de vida la China Su\u00e1rez apostando todo a su amor con Mauro Icardi\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">La dr\u00e1stica decisi\u00f3n de vida la China Su\u00e1rez apostando todo a su amor con Mauro Icardi<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>Ese detalle, simple pero cargado de significado, volvi\u00f3 a poner el foco sobre la <strong>China<\/strong>. No solo porque marca un nuevo movimiento en su vida personal, sino porque deja entrever que est\u00e1 dispuesta a reconfigurar su entorno sin mirar atr\u00e1s. Y parte de ello tambi\u00e9n apunta a la decisi\u00f3n de irse a vivir con todos sus hijos a Estambul, uno de los problemas m\u00e1s dif\u00edciles en el horizonte.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"376\" height=\"576\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/china-suarez-pampita-1.png.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-446669\" \/><\/figure>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"438\" height=\"576\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/china-suarez-pampita-2.png.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-446670\" \/><\/figure>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/romances\/el-ultimatum-de-zoe-bogach-por-su-romance-con-mauro-icardi-que-destrozo-a-la-china-suarez-tapa-su-infidelidad-y\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/Zoe-Bogach-Mauro-Icardi-China-Suarez-359x226.jpg\" alt=\"El ultim\u00e1tum de Zoe Bogach por su romance con Mauro Icardi que destroz\u00f3 a la China Su\u00e1rez: \u201cTapa su infidelidad y\u2026\u201d\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">El ultim\u00e1tum de Zoe Bogach por su romance con Mauro Icardi que destroz\u00f3 a la China Su\u00e1rez: \u201cTapa su infidelidad y\u2026\u201d<\/h5>\n<\/div>\n<p><\/a><\/div>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/romances\/revelaron-la-verdad-detras-de-la-visita-de-mauro-icardi-al-psicologo-por-sus-hijas-es-mentira-que\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/06\/Wanda-Nara-hijas-Mauro-Icardi.jpg.webp\" alt=\"Revelaron la verdad detr\u00e1s de la visita de Mauro Icardi al psic\u00f3logo por sus hijas: \u201cEs mentira que\u2026\u201d\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">Revelaron la verdad detr\u00e1s de la visita de Mauro Icardi al psic\u00f3logo por sus hijas: \u201cEs mentira que\u2026\u201d<\/h5>\n<\/div>\n<p><\/a><\/div>\n<\/p>\n<p>The post <a href=\"https:\/\/www.paparazzi.com.ar\/teve\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/\">La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud<\/a> appeared first on <a href=\"https:\/\/www.paparazzi.com.ar\">Revista Paparazzi<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los \u00faltimos meses, la China Su\u00e1rez es noticia por una serie de decisiones respecto<\/p>\n","protected":false},"author":0,"featured_media":6216,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-6215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud - Fm Gente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud - Fm Gente\" \/>\n<meta property=\"og:description\" content=\"Durante los \u00faltimos meses, la China Su\u00e1rez es noticia por una serie de decisiones respecto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/\" \/>\n<meta property=\"og:site_name\" content=\"Fm Gente\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T00:05:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud\",\"datePublished\":\"2025-10-07T00:05:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/\"},\"wordCount\":641,\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980.jpg-4.webp\",\"articleSection\":[\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/\",\"name\":\"La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud - Fm Gente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980.jpg-4.webp\",\"datePublished\":\"2025-10-07T00:05:08+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980.jpg-4.webp\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980.jpg-4.webp\",\"width\":1900,\"height\":1425},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"name\":\"Fm Gente\",\"description\":\"- Jes\u00fas Mar\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\",\"name\":\"Fm Gente\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"width\":1782,\"height\":1782,\"caption\":\"Fm Gente\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud - Fm Gente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/","og_locale":"es_ES","og_type":"article","og_title":"La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud - Fm Gente","og_description":"Durante los \u00faltimos meses, la China Su\u00e1rez es noticia por una serie de decisiones respecto","og_url":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/","og_site_name":"Fm Gente","article_published_time":"2025-10-07T00:05:08+00:00","og_image":[{"width":1900,"height":1425,"url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-4.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/#article","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/"},"author":{"name":"","@id":""},"headline":"La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud","datePublished":"2025-10-07T00:05:08+00:00","mainEntityOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/"},"wordCount":641,"publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-4.webp","articleSection":["DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/","url":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/","name":"La China Su\u00e1rez cort\u00f3 todo v\u00ednculo con Pampita y le declar\u00f3 la guerra con una pol\u00e9mica actitud - Fm Gente","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/#primaryimage"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-4.webp","datePublished":"2025-10-07T00:05:08+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/la-china-suarez-corto-todo-vinculo-con-pampita-y-le-declaro-la-guerra-con-una-polemica-actitud\/#primaryimage","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-4.webp","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980.jpg-4.webp","width":1900,"height":1425},{"@type":"WebSite","@id":"https:\/\/fmgente.com.ar\/web\/#website","url":"https:\/\/fmgente.com.ar\/web\/","name":"Fm Gente","description":"- Jes\u00fas Mar\u00eda","publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fmgente.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fmgente.com.ar\/web\/#organization","name":"Fm Gente","url":"https:\/\/fmgente.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","width":1782,"height":1782,"caption":"Fm Gente"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6215"}],"version-history":[{"count":0,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media\/6216"}],"wp:attachment":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}