{"id":6163,"date":"2025-10-05T23:05:39","date_gmt":"2025-10-06T02:05:39","guid":{"rendered":"https:\/\/fmgente.com.ar\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/"},"modified":"2025-10-05T23:05:39","modified_gmt":"2025-10-06T02:05:39","slug":"el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola","status":"publish","type":"post","link":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/","title":{"rendered":"El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot;"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.paparazzi.com.ar\/?s=%C3%81ngel+De+Brito\">\u00c1ngel De Brito<\/a><\/strong> y <strong><a href=\"https:\/\/www.paparazzi.com.ar\/?s=Fernanda+Iglesias\">Fernanda Iglesias<\/a><\/strong> volvieron a protagonizar un <a href=\"https:\/\/www.paparazzi.com.ar\/teve\/angel-de-brito-revelo-el-peor-secreto-de-la-salida-de-fernanda-iglesias-de-lam-mentirosa-loca-y\/\">tremendo cruce<\/a>. El conflicto comenz\u00f3 luego de la renuncia de Fernanda en diciembre y se intensific\u00f3 durante la reciente entrega de los Mart\u00edn Fierro. La periodista se molest\u00f3 por no ser invitada a la mesa del evento, mientras que \u00c1ngel defendi\u00f3 su decisi\u00f3n de elegir a los participantes de su mesa.<\/p>\n<p>Fernanda Iglesias, conocida por su car\u00e1cter directo, no dud\u00f3 en exponer su descontento a trav\u00e9s de redes y mensajes privados. Por su parte, \u00c1ngel De Brito respondi\u00f3 con contundencia: <em>\u201cLos dem\u00e1s no me importan que no me rompa m\u00e1s los huevos a m\u00ed, que no mienta, yo estoy en una etapa excelente y feliz con mis compa\u00f1eras\u201d<\/em>. <\/p>\n<p>El conflicto tambi\u00e9n incluy\u00f3 la filtraci\u00f3n de chats privados donde ambos discut\u00edan por distintos desencuentros profesionales. Mientras \u00c1ngel aseguraba que no deb\u00eda involucrarse en los problemas de Fernanda, ella replicaba que sent\u00eda un desagradecimiento por parte del conductor. <\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/exclusivo-el-tenso-encuentro-entre-pampita-y-nicole-neumann-por-que-ni-se-saludaron\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/pampita-14-359x226.png\" alt=\"\u00a1Exclusivo! El tenso encuentro entre Pampita y Nicole Neumann: por qu\u00e9 ni se saludaron\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">\u00a1Exclusivo! El tenso encuentro entre Pampita y Nicole Neumann: por qu\u00e9 ni se saludaron<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>Seg\u00fan explic\u00f3 uno de los panelistas en Infama, <em>\u201ctodo empez\u00f3 con la mesa de los Mart\u00edn Fierro, donde no fue invitada Fernanda, y eso desat\u00f3 el enojo\u201d<\/em>. M\u00e1s all\u00e1 de la tensi\u00f3n, \u00c1ngel consultado si la tendr\u00eda en cuenta para el programa del a\u00f1o que viene dijo: <em>\u00abA Marcela Tauro la tendr\u00eda en cuenta, a Laura Ubfal la tendr\u00eda en cuenta, a Karina Lav\u00edcoli la tendr\u00eda en cuenta\u00bb<\/em>.<\/p>\n<p><em>\u00abNo tome nada a mal de parte de ella, me chupa un huevo, estoy feliz con el Mart\u00edn Fierro, con lo que facturamos con todas las ofertas para el a\u00f1o que viene, no tengo relaci\u00f3n con ella, ya est\u00e1 termin\u00f3 hace un a\u00f1o que se fue de ac\u00e1 y se fue solita\u00bb<\/em> lanz\u00f3 \u00c1ngel sobre Fernanda.<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/del-martin-fierro-a-la-crisis-angel-de-brito-pierde-otra-pieza-clave-tras-la-salida-de-marcela-feudale-de-lam-tambien-se-va\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/Angel-1-1-359x226.jpg\" alt=\"\u00a1Del Mart\u00edn Fierro a la crisis! Angel De Brito pierde otra pieza clave tras la salida de Marcela Feudale de LAM: &quot;Tambi\u00e9n se va...&quot;\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">\u00a1Del Mart\u00edn Fierro a la crisis! Angel De Brito pierde otra pieza clave tras la salida de Marcela Feudale de LAM: \u00abTambi\u00e9n se va&#8230;\u00bb<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>\u00c1ngel resalt\u00f3 que Fernanda se arregle sola, que tenga todos sus \u00e9xitos, que haga su trabajo y que tenga su propio cuento, adem\u00e1s expres\u00f3 que el conflicto sobre quienes estaban en la mesa de los premios fue por <em>\u201cdarle espacio a quienes estaban en su programa actualmente\u201d<\/em>.<\/p>\n<p>Fernanda Iglesias, por su parte, comparti\u00f3 un comunicado en Instagram donde reafirma su personalidad directa y su compromiso con la verdad: <em>\u201cNo me pidan que no sea yo\u2026 solo voy a alzar la voz cuando lo crea necesario. Luchemos por un mundo con m\u00e1s respeto y m\u00e1s verdad\u201d<\/em>. <\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/angel-de-brito-revelo-el-peor-secreto-de-la-salida-de-fernanda-iglesias-de-lam-mentirosa-loca-y\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/Angel-de-Brito-Fernanda-Iglesias-359x226.jpg\" alt=\"\u00c1ngel de Brito revel\u00f3 el peor secreto de la salida de Fernanda Iglesias de LAM: \u201cMentirosa, loca y\u2026\u201d\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">\u00c1ngel de Brito revel\u00f3 el peor secreto de la salida de Fernanda Iglesias de LAM: \u201cMentirosa, loca y\u2026\u201d<\/h5>\n<\/div>\n<p><\/a><\/div>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/monica-farro-confeso-las-sensaciones-mas-feas-que-le-provoca-fernanda-iglesias-falsa-envidiosa-y\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/farro-iglesia-359x226.jpeg\" alt=\"M\u00f3nica Farro confes\u00f3 las sensaciones m\u00e1s feas que le provoca Fernanda Iglesias: &quot;Falsa, envidiosa y...&quot;\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">M\u00f3nica Farro confes\u00f3 las sensaciones m\u00e1s feas que le provoca Fernanda Iglesias: \u00abFalsa, envidiosa y&#8230;\u00bb<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>The post <a href=\"https:\/\/www.paparazzi.com.ar\/teve\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/\">El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot;<\/a> appeared first on <a href=\"https:\/\/www.paparazzi.com.ar\">Revista Paparazzi<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1ngel De Brito y Fernanda Iglesias volvieron a protagonizar un tremendo cruce. El conflicto comenz\u00f3<\/p>\n","protected":false},"author":0,"featured_media":6164,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-6163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot; - Fm Gente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot; - Fm Gente\" \/>\n<meta property=\"og:description\" content=\"\u00c1ngel De Brito y Fernanda Iglesias volvieron a protagonizar un tremendo cruce. El conflicto comenz\u00f3\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/\" \/>\n<meta property=\"og:site_name\" content=\"Fm Gente\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-06T02:05:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"359\" \/>\n\t<meta property=\"og:image:height\" content=\"226\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot;\",\"datePublished\":\"2025-10-06T02:05:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/\"},\"wordCount\":536,\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pampita-14-359x226-12.png\",\"articleSection\":[\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/\",\"name\":\"El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot; - Fm Gente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pampita-14-359x226-12.png\",\"datePublished\":\"2025-10-06T02:05:39+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pampita-14-359x226-12.png\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pampita-14-359x226-12.png\",\"width\":359,\"height\":226},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"name\":\"Fm Gente\",\"description\":\"- Jes\u00fas Mar\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\",\"name\":\"Fm Gente\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"width\":1782,\"height\":1782,\"caption\":\"Fm Gente\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot; - Fm Gente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/","og_locale":"es_ES","og_type":"article","og_title":"El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot; - Fm Gente","og_description":"\u00c1ngel De Brito y Fernanda Iglesias volvieron a protagonizar un tremendo cruce. El conflicto comenz\u00f3","og_url":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/","og_site_name":"Fm Gente","article_published_time":"2025-10-06T02:05:39+00:00","og_image":[{"width":359,"height":226,"url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-12.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/#article","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/"},"author":{"name":"","@id":""},"headline":"El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot;","datePublished":"2025-10-06T02:05:39+00:00","mainEntityOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/"},"wordCount":536,"publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-12.png","articleSection":["DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/","url":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/","name":"El tremendo insulto de \u00c1ngel De Brito a una de sus ex angelitas: &quot;que se arregle sola&quot; - Fm Gente","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/#primaryimage"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-12.png","datePublished":"2025-10-06T02:05:39+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/el-tremendo-insulto-de-angel-de-brito-a-una-de-sus-ex-angelitas-que-se-arregle-sola\/#primaryimage","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-12.png","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-12.png","width":359,"height":226},{"@type":"WebSite","@id":"https:\/\/fmgente.com.ar\/web\/#website","url":"https:\/\/fmgente.com.ar\/web\/","name":"Fm Gente","description":"- Jes\u00fas Mar\u00eda","publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fmgente.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fmgente.com.ar\/web\/#organization","name":"Fm Gente","url":"https:\/\/fmgente.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","width":1782,"height":1782,"caption":"Fm Gente"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6163"}],"version-history":[{"count":0,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media\/6164"}],"wp:attachment":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}