{"id":6122,"date":"2025-10-05T11:08:26","date_gmt":"2025-10-05T14:08:26","guid":{"rendered":"https:\/\/fmgente.com.ar\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/"},"modified":"2025-10-05T11:08:26","modified_gmt":"2025-10-05T14:08:26","slug":"la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y","status":"publish","type":"post","link":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/","title":{"rendered":"La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d"},"content":{"rendered":"<p>La separaci\u00f3n de <strong>Nico V\u00e1zquez<\/strong> y <strong>Gimena Accardi<\/strong> fue sin dudas una de las rupturas m\u00e1s fuertes del mundo del espect\u00e1culo. Tan inesperada que dej\u00f3 un efecto colateral poco imaginado, porque decidieron tomar caminos diferentes tras 18 a\u00f1os en pareja y se dijeron muchas cosas alrededor, involucrando a terceros en discordia.<\/p>\n<p>De hecho la propia <strong>Gimena<\/strong> admiti\u00f3 hace unas semanas en OLGA que le fue infiel a <strong><a href=\"https:\/\/www.paparazzi.com.ar\/horoscopo\/nuevo-amor-y-paternidad-pitty-la-numerolga-confirmo-dos-bombas-sobre-nico-vazquez-tras-su-separacion\/\">Nicol\u00e1s<\/a><\/strong>. Y si bien se dijo que se trataba de un <em>\u201crandom\u201d<\/em>, varios nombres fueron vinculados a la vida privada de la conductora. Lo mismo pas\u00f3 con el actor, que en su momento fue vinculado con <strong>Dai Fern\u00e1ndez<\/strong>, su compa\u00f1era en <strong><em>Rocky<\/em><\/strong>, la obra que dirige y protagoniza.<\/p>\n<p>Lo cierto es que <strong>Nico<\/strong> desminti\u00f3 categ\u00f3ricamente que est\u00e9 teniendo un romance con <strong>Dai<\/strong>, aunque luego de la separaci\u00f3n de <strong><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/nico-vazquez-conto-la-charla-privada-que-tuvo-con-sylvester-stallone-me-pidio-que\/\">Gime<\/a><\/strong> se dio una situaci\u00f3n inesperada: la tambi\u00e9n ruptura de la actriz con su novio, <strong>Gonzalo Gerber<\/strong>. Esto para algunos fue tomado como una se\u00f1al, y aunque tambi\u00e9n lo negaron, todo parec\u00eda encajar a la perfecci\u00f3n.<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/videos\/exclusivo-marcelo-polino-hablo-como-nunca-de-su-vida-intima-y-conto-cuando-fue-la-ultima-vez-que-tuvo-sexo-con-una-mujer\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/IMG_5980-359x226.jpg\" alt=\"\u00a1Exclusivo! Marcelo Polino habl\u00f3 como nunca de su vida \u00edntima y cont\u00f3 cu\u00e1ndo fue la \u00faltima vez que tuvo sexo con una mujer\u00a0\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">\u00a1Exclusivo! Marcelo Polino habl\u00f3 como nunca de su vida \u00edntima y cont\u00f3 cu\u00e1ndo fue la \u00faltima vez que tuvo sexo con una mujer\u00a0<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>M\u00e1s all\u00e1 de los rumores y las especulaciones a su alrededor, la propia <strong><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/en-quien-se-refugia-nico-vazquez-tras-separarse-de-gime-accardi-todas-las-fotos\/\">Dai<\/a><\/strong> fue consultada por su relaci\u00f3n con <strong>V\u00e1zquez<\/strong> y explic\u00f3 que comparten mucho tiempo juntos, teniendo muchas charlas antes de salir al teatro a hacer sus funciones. Y defini\u00f3 que ambos se dan una contenci\u00f3n amistosa dentro del duelo amoroso que viven.<\/p>\n<h2 class=\"wp-block-heading\">NICO V\u00c1ZQUEZ REVEL\u00d3 LA PROMESA QUE LE CUMPLI\u00d3 A DAI FERN\u00c1NDEZ<\/h2>\n<p>En este punto, en los \u00faltimos d\u00edas <strong>Nicol\u00e1s<\/strong> visit\u00f3 el programa Nadie dice nada de Luzu y charl\u00f3 con <strong>Nico Occhiato <\/strong>sobre el gran \u00e9xito que est\u00e1 teniendo con <strong><em>Rocky<\/em><\/strong>. Lo fuerte es que, mientras hablaba de c\u00f3mo fue surgiendo este ambicioso pero fant\u00e1stico proyecto teatral, profundiz\u00f3 sobre el fuerte v\u00ednculo que tiene con <strong>Dai<\/strong> y la promesa que le hizo en su momento.<\/p>\n<p>Mientras hablaba del d\u00eda que le aprobaron el proyecto de su obra, <strong>Nico<\/strong> revel\u00f3: <em>\u201cA los 15-20 d\u00edas que yo decido hacer Rocky, me la cruzo a Dai haciendo Tootsie, la agarro de la mano y le digo \u2018Compa, rez\u00e1\u2026 si me sale algo a m\u00ed, te sale a vos, quiero que hagas algo conmigo\u2019. Y ella me dice \u2018Ah, bueno, buen\u00edsimo\u2019&#8230; Me dice \u2018\u00bfEs ensamble?\u2019, \u2018No, protagonista, pero no te puedo decir, si me sale a m\u00ed te sale a vos\u2019&#8230; as\u00ed la tuve tres meses\u201d<\/em>.<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/horoscopo\/nuevo-amor-y-paternidad-pitty-la-numerolga-confirmo-dos-bombas-sobre-nico-vazquez-tras-su-separacion\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/Nuevo-amor-y-paternidad-Pitty-La-Numerolga-confirmo-dos-bombas-sobre-Nico-Vazquez-tras-su-separacion-359x226.jpg\" alt=\"Nuevo amor y paternidad: Pitty La Numer\u00f3lga confirm\u00f3 dos bombas sobre Nico V\u00e1zquez tras su separaci\u00f3n\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">Nuevo amor y paternidad: Pitty La Numer\u00f3lga confirm\u00f3 dos bombas sobre Nico V\u00e1zquez tras su separaci\u00f3n<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p><em>\u201cHabr\u00eda que llamarla al aire ahora porque ella me preguntaba todos los d\u00edas qu\u00e9 era\u2026 y un d\u00eda la siento y le digo \u2018\u00bfQu\u00e9 pens\u00e1s que puede ser?\u2019, yo no pod\u00eda hablar, ten\u00eda prohibido hablar del tema porque era muy delicado si se filtraba, por los derechos\u2026 ten\u00eda mucho cagazo. O capaz que le dec\u00eda el proyecto y se me bajaba\u201d<\/em>, sigui\u00f3 <strong>Nicol\u00e1s<\/strong>.<\/p>\n<p>Pero esa charla con <strong>Dai<\/strong> termin\u00f3 para bien, porque cuando <strong>V\u00e1zquez<\/strong> le dijo que la propuesta laboral que ten\u00eda para ella se trataba de <strong><em>Rocky<\/em><\/strong>, todo encaj\u00f3 a la perfecci\u00f3n:<em> \u201cCuando se lo digo, se le llenaron los ojos de l\u00e1grimas y me dijo que era de sus pel\u00edculas favoritas, que amaba el personaje de ella (en referencia a Adrian, el papel de Talia Shire que Dai interpreta en la obra). Ah\u00ed empez\u00f3 todo\u201d<\/em>.<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/nico-vazquez-conto-la-charla-privada-que-tuvo-con-sylvester-stallone-me-pidio-que\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/10\/nico-vazquez-1-359x226.png\" alt=\"Nico V\u00e1zquez cont\u00f3 la charla privada que tuvo con Sylvester Stallone: &quot;Me pidi\u00f3 que\u2026&quot;\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">Nico V\u00e1zquez cont\u00f3 la charla privada que tuvo con Sylvester Stallone: \u00abMe pidi\u00f3 que\u2026\u00bb<\/h5>\n<\/div>\n<p><\/a><\/div>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/en-quien-se-refugia-nico-vazquez-tras-separarse-de-gime-accardi-todas-las-fotos\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/image-252-359x226.png\" alt=\"En qui\u00e9n se refugia Nico V\u00e1zquez tras separarse de Gime Accardi: todas las fotos\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">En qui\u00e9n se refugia Nico V\u00e1zquez tras separarse de Gime Accardi: todas las fotos<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>The post <a href=\"https:\/\/www.paparazzi.com.ar\/romances\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/\">La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d<\/a> appeared first on <a href=\"https:\/\/www.paparazzi.com.ar\">Revista Paparazzi<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La separaci\u00f3n de Nico V\u00e1zquez y Gimena Accardi fue sin dudas una de las rupturas<\/p>\n","protected":false},"author":0,"featured_media":6123,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-6122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d - Fm Gente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d - Fm Gente\" \/>\n<meta property=\"og:description\" content=\"La separaci\u00f3n de Nico V\u00e1zquez y Gimena Accardi fue sin dudas una de las rupturas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/\" \/>\n<meta property=\"og:site_name\" content=\"Fm Gente\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-05T14:08:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980-359x226-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"359\" \/>\n\t<meta property=\"og:image:height\" content=\"226\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d\",\"datePublished\":\"2025-10-05T14:08:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/\"},\"wordCount\":703,\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980-359x226-25.jpg\",\"articleSection\":[\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/\",\"name\":\"La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d - Fm Gente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980-359x226-25.jpg\",\"datePublished\":\"2025-10-05T14:08:26+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980-359x226-25.jpg\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG_5980-359x226-25.jpg\",\"width\":359,\"height\":226},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"name\":\"Fm Gente\",\"description\":\"- Jes\u00fas Mar\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\",\"name\":\"Fm Gente\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"width\":1782,\"height\":1782,\"caption\":\"Fm Gente\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d - Fm Gente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/","og_locale":"es_ES","og_type":"article","og_title":"La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d - Fm Gente","og_description":"La separaci\u00f3n de Nico V\u00e1zquez y Gimena Accardi fue sin dudas una de las rupturas","og_url":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/","og_site_name":"Fm Gente","article_published_time":"2025-10-05T14:08:26+00:00","og_image":[{"width":359,"height":226,"url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980-359x226-25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/#article","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/"},"author":{"name":"","@id":""},"headline":"La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d","datePublished":"2025-10-05T14:08:26+00:00","mainEntityOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/"},"wordCount":703,"publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980-359x226-25.jpg","articleSection":["DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/","url":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/","name":"La promesa de Nico V\u00e1zquez a Dai Fern\u00e1ndez tras separarse de Gimena Accardi: \u201cLa tom\u00e9 de la mano y\u2026\u201d - Fm Gente","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/#primaryimage"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980-359x226-25.jpg","datePublished":"2025-10-05T14:08:26+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/la-promesa-de-nico-vazquez-a-dai-fernandez-tras-separarse-de-gimena-accardi-la-tome-de-la-mano-y\/#primaryimage","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980-359x226-25.jpg","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/IMG_5980-359x226-25.jpg","width":359,"height":226},{"@type":"WebSite","@id":"https:\/\/fmgente.com.ar\/web\/#website","url":"https:\/\/fmgente.com.ar\/web\/","name":"Fm Gente","description":"- Jes\u00fas Mar\u00eda","publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fmgente.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fmgente.com.ar\/web\/#organization","name":"Fm Gente","url":"https:\/\/fmgente.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","width":1782,"height":1782,"caption":"Fm Gente"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6122"}],"version-history":[{"count":0,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media\/6123"}],"wp:attachment":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}