{"id":6118,"date":"2025-10-05T09:06:03","date_gmt":"2025-10-05T12:06:03","guid":{"rendered":"https:\/\/fmgente.com.ar\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/"},"modified":"2025-10-05T09:06:03","modified_gmt":"2025-10-05T12:06:03","slug":"elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien","status":"publish","type":"post","link":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/","title":{"rendered":"Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n &#8230;\u201d"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.paparazzi.com.ar\/?s=Elba+Marcovecchio\">Elba Marcovecchio<\/a><\/strong> volvi\u00f3 a la televisi\u00f3n y lo hizo nada menos que en la mesa de <em><a href=\"https:\/\/www.paparazzi.com.ar\/?s=Mirtha+Legrand\">Mirtha Legrand<\/a><\/em>, donde habl\u00f3 sin filtros sobre uno de los momentos m\u00e1s comentados de las \u00faltimas semanas: su encuentro con la hija de Jorge Lanata, Lola, durante la \u00faltima edici\u00f3n de los <a href=\"https:\/\/www.paparazzi.com.ar\/?s=Premios+Mart%C3%ADn+Fierro\">Premios Mart\u00edn Fierro<\/a>.<\/p>\n<p>Con la serenidad que la caracteriza, la abogada record\u00f3 el episodio y sorprendi\u00f3 al relatar: <em>\u201cNos cruzamos con Allegra y con Lola, nadie lo sabe\u2026 Nos cruzamos con Lola yendo al toilette, yo estaba con Allegra, y nos saludamos. No podr\u00eda decir qui\u00e9n salud\u00f3 a qui\u00e9n, fue algo cognitivo, pero s\u00ed, nos saludamos\u201d.<\/em><\/p>\n<p>Mirtha, siempre directa, le pregunt\u00f3:<em> \u201c\u00bfY de qu\u00e9 te acusan estas chicas? \u00bfNunca te quisieron?\u201d.<\/em> Fue entonces cuando Elba se sincer\u00f3: <em>\u201cAhora estamos en un periodo de paz, que espero que contin\u00fae, porque la verdad el a\u00f1o pasado fue muy oscuro\u00bb.<\/em><\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/exclusivo-el-tenso-encuentro-entre-pampita-y-nicole-neumann-por-que-ni-se-saludaron\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/pampita-14-359x226.png\" alt=\"\u00a1Exclusivo! El tenso encuentro entre Pampita y Nicole Neumann: por qu\u00e9 ni se saludaron\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">\u00a1Exclusivo! El tenso encuentro entre Pampita y Nicole Neumann: por qu\u00e9 ni se saludaron<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>Y sigui\u00f3:<em> \u00abLastim\u00f3 much\u00edsimo a mis hijos y lo digo ahora por qu\u00e9 en ese momento estaba totalmente concentrada en Jorge. \u00c9l me necesitaba, y quiz\u00e1s descuid\u00e9 un poco a mis hijos, y eso es lo que m\u00e1s me pesa\u201d.<\/em> Marcovecchio explic\u00f3 que durante la enfermedad del periodista vivi\u00f3 momentos de enorme presi\u00f3n emocional, lo que la llev\u00f3 a priorizar el cuidado de Lanata sobre otras cuestiones familiares. <\/p>\n<p><em>\u201cMe acusaron de todo, fue un periodo muy duro. Y esas acusaciones, en vez de quedar en el \u00e1mbito privado, se hicieron p\u00fablicas. El da\u00f1o fue enorme: a m\u00ed, a mis hijos, a mi mam\u00e1, a mis amigos que me contuvieron. Pero ahora, por suerte, todo se calm\u00f3\u201d<\/em>, afirm\u00f3 con honestidad.<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/elba-marcovecchio-revelo-que-sintio-al-ver-a-las-hijas-de-jorge-lanata-en-los-martin-fierro-estaba-muy\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/Elba-y-las-hijas-de-Lanata-359x226.jpg\" alt=\"Elba Marcovecchio revel\u00f3 qu\u00e9 sinti\u00f3 al ver a las hijas de Jorge Lanata en los Mart\u00edn Fierro: &quot;Estaba muy\u2026&quot;\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">Elba Marcovecchio revel\u00f3 qu\u00e9 sinti\u00f3 al ver a las hijas de Jorge Lanata en los Mart\u00edn Fierro: \u00abEstaba muy\u2026\u00bb<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>La abogada tambi\u00e9n aprovech\u00f3 para hacer una reflexi\u00f3n sobre los conflictos familiares: <em>\u201cSiempre remarco esto en las causas de familia: las turbulencias que se dan al principio, cuando hay enojos, deber\u00edan quedarse en el \u00e1mbito privado. Porque a veces esas turbulencias pasan, pero los coletazos dejan huellas que no se borran\u201d<\/em>, se\u00f1al\u00f3.<\/p>\n<p>El testimonio de Elba conmovi\u00f3 a los presentes, incluida Mirtha, que la escuch\u00f3 atentamente. Con esta declaraci\u00f3n, la abogada mostr\u00f3 un costado humano y vulnerable, reconociendo los errores, el dolor y la esperanza de reconstruir la paz familiar tras un a\u00f1o de gran exposici\u00f3n medi\u00e1tica y duelo.<\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/el-desgarrador-mensaje-de-elba-marcovecchio-por-el-cumpleanos-de-jorge-lanata-nos-quedo\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/01\/Elba-Marcovecchio-Jorge-Lanata-1-359x226.jpg\" alt=\"El desgarrador mensaje de Elba Marcovecchio por el cumplea\u00f1os de Jorge Lanata: \u201cNos qued\u00f3\u2026&quot;\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">El desgarrador mensaje de Elba Marcovecchio por el cumplea\u00f1os de Jorge Lanata: \u201cNos qued\u00f3\u2026\u00bb<\/h5>\n<\/div>\n<p><\/a><\/div>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.paparazzi.com.ar\/teve\/elba-marcovecchio-confirmo-que-tiene-mensajes-comprometedores-de-romina-manguel-a-jorge-lanata\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.paparazzi.com.ar\/wp-content\/uploads\/2025\/09\/Elba-Marcovecchio-Romina-Manguel-359x226.jpg\" alt=\"Elba Marcovecchio confirm\u00f3 que tiene mensajes comprometedores de Romina Manguel a Jorge Lanata\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">Elba Marcovecchio confirm\u00f3 que tiene mensajes comprometedores de Romina Manguel a Jorge Lanata<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p>The post <a href=\"https:\/\/www.paparazzi.com.ar\/teve\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/\">Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n &#8230;\u201d<\/a> appeared first on <a href=\"https:\/\/www.paparazzi.com.ar\">Revista Paparazzi<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elba Marcovecchio volvi\u00f3 a la televisi\u00f3n y lo hizo nada menos que en la mesa<\/p>\n","protected":false},"author":0,"featured_media":6119,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-6118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n ...\u201d - Fm Gente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n ...\u201d - Fm Gente\" \/>\n<meta property=\"og:description\" content=\"Elba Marcovecchio volvi\u00f3 a la televisi\u00f3n y lo hizo nada menos que en la mesa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/\" \/>\n<meta property=\"og:site_name\" content=\"Fm Gente\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-05T12:06:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-10.png\" \/>\n\t<meta property=\"og:image:width\" content=\"359\" \/>\n\t<meta property=\"og:image:height\" content=\"226\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n &#8230;\u201d\",\"datePublished\":\"2025-10-05T12:06:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/\"},\"wordCount\":501,\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pampita-14-359x226-10.png\",\"articleSection\":[\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/\",\"name\":\"Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n ...\u201d - Fm Gente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pampita-14-359x226-10.png\",\"datePublished\":\"2025-10-05T12:06:03+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pampita-14-359x226-10.png\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pampita-14-359x226-10.png\",\"width\":359,\"height\":226},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"name\":\"Fm Gente\",\"description\":\"- Jes\u00fas Mar\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\",\"name\":\"Fm Gente\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"width\":1782,\"height\":1782,\"caption\":\"Fm Gente\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n ...\u201d - Fm Gente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/","og_locale":"es_ES","og_type":"article","og_title":"Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n ...\u201d - Fm Gente","og_description":"Elba Marcovecchio volvi\u00f3 a la televisi\u00f3n y lo hizo nada menos que en la mesa","og_url":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/","og_site_name":"Fm Gente","article_published_time":"2025-10-05T12:06:03+00:00","og_image":[{"width":359,"height":226,"url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-10.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/#article","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/"},"author":{"name":"","@id":""},"headline":"Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n &#8230;\u201d","datePublished":"2025-10-05T12:06:03+00:00","mainEntityOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/"},"wordCount":501,"publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-10.png","articleSection":["DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/","url":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/","name":"Elba Marcovecchio revel\u00f3 el tenso cruce con la hija de Jorge Lanata: \u201cNo puedo decir qui\u00e9n ...\u201d - Fm Gente","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/#primaryimage"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-10.png","datePublished":"2025-10-05T12:06:03+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/elba-marcovecchio-revelo-el-tenso-cruce-con-la-hija-de-jorge-lanata-no-puedo-decir-quien\/#primaryimage","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-10.png","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2025\/10\/pampita-14-359x226-10.png","width":359,"height":226},{"@type":"WebSite","@id":"https:\/\/fmgente.com.ar\/web\/#website","url":"https:\/\/fmgente.com.ar\/web\/","name":"Fm Gente","description":"- Jes\u00fas Mar\u00eda","publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fmgente.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fmgente.com.ar\/web\/#organization","name":"Fm Gente","url":"https:\/\/fmgente.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","width":1782,"height":1782,"caption":"Fm Gente"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/comments?post=6118"}],"version-history":[{"count":0,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/6118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media\/6119"}],"wp:attachment":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media?parent=6118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/categories?post=6118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/tags?post=6118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}