{"id":23376,"date":"2026-05-13T10:06:09","date_gmt":"2026-05-13T13:06:09","guid":{"rendered":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/"},"modified":"2026-05-13T10:06:09","modified_gmt":"2026-05-13T13:06:09","slug":"escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi","status":"publish","type":"post","link":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/","title":{"rendered":"Esc\u00e1ndalo en Punta del Este: una masajista uruguaya denunci\u00f3 fiestas sexuales ligadas al c\u00edrculo \u00edntimo de Silvio Berlusconi"},"content":{"rendered":"<p>Durante a\u00f1os, Punta del Este cultiv\u00f3 una imagen de refugio sofisticado del jet set internacional: mansiones frente al mar, empresarios multimillonarios, celebridades europeas y fiestas blindadas al ojo p\u00fablico. Pero ahora, un testimonio explosivo volvi\u00f3 a poner el foco sobre el costado m\u00e1s oscuro de ese universo de lujo.<\/p>\n<p><strong>Graciela de los Santos Torres<\/strong>, una masajista uruguaya de 46 a\u00f1os, asegur\u00f3 haber trabajado durante dos d\u00e9cadas en la finca \u201cGin Tonic\u201d, propiedad del empresario italiano <strong>Giuseppe Cipriani<\/strong>, y revel\u00f3 detalles de presuntas fiestas sexuales organizadas all\u00ed por <strong>Nicole Minetti<\/strong>, una hist\u00f3rica colaboradora y allegada de <strong>Silvio Berlusconi.<\/strong><\/p>\n<p>La mujer habl\u00f3 con el diario italiano Il Fatto Quotidiano y describi\u00f3 un entramado que involucrar\u00eda escorts, empresarios argentinos, brasile\u00f1os, italianos y uruguayos, adem\u00e1s de consumo de alcohol y drogas en encuentros privados realizados en Punta del Este.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"658\" height=\"576\" src=\"https:\/\/www.revistagente.com\/wp-content\/uploads\/2026\/05\/Captura-de-pantalla-2026-05-13-a-las-08.45.07.png.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-654321\" style=\"aspect-ratio:1.1423959633226628;width:725px;height:auto\" \/><figcaption class=\"wp-element-caption\">La nota en Il Fatto Quotidiano a la masajista Graciela de los Santos que volvi\u00f3 a complicar a Nicole Minetti. <\/figcaption><\/figure>\n<h2 class=\"wp-block-heading\">Qui\u00e9n es Nicole Minetti, la mujer vinculada al esc\u00e1ndalo \u201cBunga Bunga\u201d<\/h2>\n<p><strong>Nicole Minetti<\/strong> (41) fue una de las figuras m\u00e1s controversiales alrededor de Silvio Berlusconi durante los a\u00f1os m\u00e1s escandalosos de su carrera pol\u00edtica. Ex higienista dental convertida en consejera regional en Lombard\u00eda, salt\u00f3 a la fama internacional por su presunta participaci\u00f3n en las fiestas privadas del ex premier italiano y es pareja de Cipriani.<\/p>\n<p>En Italia fue condenada por facilitamiento e instigaci\u00f3n a la prostituci\u00f3n dentro del llamado caso \u201cBunga Bunga\u201d, el entramado de fiestas sexuales que sacudi\u00f3 a la pol\u00edtica italiana y termin\u00f3 erosionando a\u00fan m\u00e1s la imagen p\u00fablica de Berlusconi. Sin embargo, tiempo despu\u00e9s recibi\u00f3 un indulto otorgado por el presidente Sergio Mattarella.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"650\" height=\"605\" src=\"https:\/\/www.revistagente.com\/wp-content\/uploads\/2026\/05\/Captura-de-pantalla-2026-05-13-a-las-08.46.38.png.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-654320\" style=\"width:725px;height:auto\" \/><figcaption class=\"wp-element-caption\">Nicole Minetti, la excolaboradora de Silvio Berlusconi, bajo la lupa luego del indulto. <\/figcaption><\/figure>\n<p>Seg\u00fan el testimonio de De los Santos Torres, Minetti continu\u00f3 organizando encuentros similares fuera de Italia.<strong> \u201cNo cambi\u00f3 nunca su vida, sino que continu\u00f3 haciendo lo mismo por lo que fue condenada en Italia\u201d<\/strong>, afirm\u00f3 la masajista.<\/p>\n<h2 class=\"wp-block-heading\">\u201cHab\u00eda un sistema\u201d: el relato sobre las fiestas en la finca de Jos\u00e9 Ignacio<\/h2>\n<p>La mujer describi\u00f3 una din\u00e1mica aceitada y sostenida en el tiempo. Seg\u00fan dijo, a la finca de Cipriani llegaban j\u00f3venes desde distintos pa\u00edses de Sudam\u00e9rica y Europa para participar de encuentros con hombres poderosos.<\/p>\n<p>\u201cHab\u00eda un sistema, y ese era un lugar al que llegaban continuamente chicas desde Brasil, Argentina y de Italia para empresarios ricos, pol\u00edticos y otras personas de relevancia; algunas con vuelos privados. Hab\u00eda alcohol, droga y sexo\u201d, sostuvo.<\/p>\n<p>El relato tambi\u00e9n apunta a un mecanismo de selecci\u00f3n de mujeres que, seg\u00fan ella, estaba coordinado directamente por Minetti. \u201cElla viv\u00eda por largos per\u00edodos all\u00ed y todos la conoc\u00edan. Y era ella quien eleg\u00eda a las chicas: \u2018Esta chica me gusta\u2026 esta no\u2019\u201d, asegur\u00f3.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"702\" height=\"483\" src=\"https:\/\/www.revistagente.com\/wp-content\/uploads\/2026\/05\/Captura-de-pantalla-2026-05-13-a-las-08.53.59.png.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-654322\" \/><figcaption class=\"wp-element-caption\">Minetti, condenada anteriormente por inducci\u00f3n a la prostituci\u00f3n y malversaci\u00f3n, recibi\u00f3 el indulto por el presidente italiano Sergio Mattarella para cuidar a un menor que hab\u00eda adoptado junto a Cipriani. <\/figcaption><\/figure>\n<p>Las declaraciones reconstruyen un ecosistema de excesos que, seg\u00fan su versi\u00f3n, funcionaba con absoluta naturalidad dentro del c\u00edrculo frecuente de visitantes internacionales de alto poder adquisitivo. <\/p>\n<h2 class=\"wp-block-heading\">La conexi\u00f3n con empresarios argentinos y el jet set regional<\/h2>\n<p>Uno de los puntos que m\u00e1s impacto gener\u00f3 en Italia fue la referencia a la presencia habitual de empresarios argentinos y figuras del jet set sudamericano. <strong>\u201cAl principio eran empresarios y el jet-set argentino, brasile\u00f1o y europeo; pero despu\u00e9s tambi\u00e9n estaban los \u2018amigos de la casa\u2019\u201d<\/strong>, relat\u00f3 de los Santos Torres. <\/p>\n<p>Punta del Este funcion\u00f3 hist\u00f3ricamente como enclave de encuentro para magnates europeos durante las temporadas de verano. La combinaci\u00f3n entre privacidad, mansiones alejadas y circulaci\u00f3n constante de vuelos privados convirti\u00f3 a Jos\u00e9 Ignacio en uno de los destinos preferidos de las grandes fortunas internacionales.<\/p>\n<p>El nombre de Giuseppe Cipriani, heredero del hist\u00f3rico imperio gastron\u00f3mico Harry\u2019s Bar de Venecia y creador de la cadena Cipriani, aparece en el centro del escenario porque la finca se\u00f1alada pertenece a \u00e9l. Sin embargo, hasta el momento no existe ninguna acusaci\u00f3n judicial p\u00fablica en Uruguay vinculada a los hechos narrados por la masajista.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.revistagente.com\/wp-content\/uploads\/2026\/05\/Guiseppe-Cipriani.jpg.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-654327\" style=\"width:725px;height:auto\" \/><figcaption class=\"wp-element-caption\">El empresario Giuseppe Cipriani vive en Punta del Este junto a su mujer, Nicole Minetti y el hijo que adoptaron. <\/figcaption><\/figure>\n<p>Recordemos que en la famosa chacra este\u00f1a de Cipriani, cada a\u00f1o se celebra la famosa \u00abfiesta Cipriani\u00bb a puertas cerradas, un encuentro de ricos, famosos y socialit\u00e9s donde los celulares est\u00e1n prohibidos y todos quieren entrar. <\/p>\n<h2 class=\"wp-block-heading\">El costado m\u00e1s inquietante del testimonio: menores, miedo y pactos de silencio<\/h2>\n<p>Entre las declaraciones m\u00e1s delicadas aparece el relato de una joven que, seg\u00fan De los Santos Torres, habr\u00eda llegado siendo menor de edad.<\/p>\n<p><strong>\u201cUna chica me cont\u00f3 entre l\u00e1grimas que lleg\u00f3 a Punta del Este cuando ten\u00eda 15 a\u00f1os, tra\u00edda por su propia madre. Me habl\u00f3 de drogas, depresi\u00f3n y de a\u00f1os muy dif\u00edciles\u201d<\/strong>, relat\u00f3 el citado medio italiano.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.revistagente.com\/wp-content\/uploads\/2023\/06\/berlusconi.jpg.webp\" loading=\"lazy\" alt=\"\" class=\"wp-image-432147\" \/><figcaption class=\"wp-element-caption\">Silvio Berlusconi\u00a0(1936\u20132023) fue un magnate de los medios de comunicaci\u00f3n y pol\u00edtico italiano que se convirti\u00f3 en primer ministro en tres ocasiones (1994, 2001\u20132006 y 2008\u20132011). <\/figcaption><\/figure>\n<p>La masajista tambi\u00e9n asegur\u00f3 que exist\u00edan presuntos favores hacia funcionarios migratorios y describi\u00f3 un clima de silencio sostenido por miedo y poder econ\u00f3mico. \u00abAlgunos de ellos ven\u00edan a mi casa a que los masajeara&#8230; Todo era considerado normal\u00bb, sum\u00f3. <\/p>\n<p>Adem\u00e1s, narr\u00f3 c\u00f3mo era la mec\u00e1nica dentro de la finca Cipriani. \u00abA veces masajeaba justo debajo de la ventana de la habitaci\u00f3n privada de Cipriani. \u00c9l, a su vez, siempre pretend\u00eda de m\u00ed masajes cada vez m\u00e1s \u00edntimos, y hasta en una ocasi\u00f3n me ped\u00eda masajes er\u00f3ticos. Cuando me negu\u00e9, comenzaron los problemas\u00bb, agreg\u00f3 De los Santos Torres. <\/p>\n<p>\u201cAcept\u00e9 dinero porque quer\u00eda salir de ese ambiente t\u00f3xico cuanto antes. No fui valiente. Me qued\u00e9 en mi casa un a\u00f1o por miedo a represalias\u201d, admiti\u00f3 la masajista al referirse a los miles de d\u00f3lares que recibi\u00f3 en su momento a cambio de un acuerdo de confidencialidad. <\/p>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.revistagente.com\/entretenimiento\/celebrities\/sean-diddy-combs-las-claves-del-caso-que-lo-llevo-a-la-carcel-y-que-dijeron-los-famosos-involucrados-en-las-fiestas-sexuales\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.revistagente.com\/wp-content\/uploads\/2024\/10\/Sean-Diddy-Combs-359x292.jpg\" alt=\"Sean &quot;Diddy&quot; Combs: las claves del caso que lo llev\u00f3 a la c\u00e1rcel y qu\u00e9 dijeron los famosos involucrados en las fiestas sexuales\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">Sean \u00abDiddy\u00bb Combs: las claves del caso que lo llev\u00f3 a la c\u00e1rcel y qu\u00e9 dijeron los famosos involucrados en las fiestas sexuales<\/h5>\n<\/div>\n<p><\/a><\/div>\n<div class=\"mt-box \">\n<h4 class=\"mt-heading\">Mir\u00e1 Tambi\u00e9n<\/h4>\n<p><a href=\"https:\/\/www.revistagente.com\/actualidad\/fiestas-vip-lujo-extremo-y-servicios-bajo-la-lupa-como-operaba-la-exclusiva-red-de-prostitucion-que-seducia-a-futbolistas-y-deportistas-en-milan\/\"><\/p>\n<div class=\"mt-content\">\n<div class=\"mt-image-container\"><img decoding=\"async\" src=\"https:\/\/www.revistagente.com\/wp-content\/uploads\/2026\/04\/futbol-escandalo-gente-1-359x292.jpg\" alt=\"Fiestas VIP, lujo extremo y servicios bajo la lupa: c\u00f3mo operaba la exclusiva &quot;red de prostituci\u00f3n&quot; que seduc\u00eda a futbolistas y deportistas en Mil\u00e1n\" class=\"mt-image\" loading=\"lazy\" \/><\/div>\n<h5 class=\"mt-title\">Fiestas VIP, lujo extremo y servicios bajo la lupa: c\u00f3mo operaba la exclusiva \u00abred de prostituci\u00f3n\u00bb que seduc\u00eda a futbolistas y deportistas en Mil\u00e1n<\/h5>\n<\/div>\n<p><\/a><\/div>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a\u00f1os, Punta del Este cultiv\u00f3 una imagen de refugio sofisticado del jet set internacional:<\/p>\n","protected":false},"author":0,"featured_media":23377,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1797],"tags":[],"class_list":["post-23376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esc\u00e1ndalo en Punta del Este: una masajista uruguaya denunci\u00f3 fiestas sexuales ligadas al c\u00edrculo \u00edntimo de Silvio Berlusconi - Fm Gente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esc\u00e1ndalo en Punta del Este: una masajista uruguaya denunci\u00f3 fiestas sexuales ligadas al c\u00edrculo \u00edntimo de Silvio Berlusconi - Fm Gente\" \/>\n<meta property=\"og:description\" content=\"Durante a\u00f1os, Punta del Este cultiv\u00f3 una imagen de refugio sofisticado del jet set internacional:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/\" \/>\n<meta property=\"og:site_name\" content=\"Fm Gente\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T13:06:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Esc\u00e1ndalo en Punta del Este: una masajista uruguaya denunci\u00f3 fiestas sexuales ligadas al c\u00edrculo \u00edntimo de Silvio Berlusconi\",\"datePublished\":\"2026-05-13T13:06:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/\"},\"wordCount\":1131,\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Captura-de-pantalla-2026-05-13-a-las-08.45.07.png.webp\",\"articleSection\":[\"ESPECTACULO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/\",\"name\":\"Esc\u00e1ndalo en Punta del Este: una masajista uruguaya denunci\u00f3 fiestas sexuales ligadas al c\u00edrculo \u00edntimo de Silvio Berlusconi - Fm Gente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Captura-de-pantalla-2026-05-13-a-las-08.45.07.png.webp\",\"datePublished\":\"2026-05-13T13:06:09+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Captura-de-pantalla-2026-05-13-a-las-08.45.07.png.webp\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Captura-de-pantalla-2026-05-13-a-las-08.45.07.png.webp\",\"width\":658,\"height\":576},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"name\":\"Fm Gente\",\"description\":\"- Jes\u00fas Mar\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#organization\",\"name\":\"Fm Gente\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"contentUrl\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-logo-sombra2.png\",\"width\":1782,\"height\":1782,\"caption\":\"Fm Gente\"},\"image\":{\"@id\":\"https:\\\/\\\/fmgente.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esc\u00e1ndalo en Punta del Este: una masajista uruguaya denunci\u00f3 fiestas sexuales ligadas al c\u00edrculo \u00edntimo de Silvio Berlusconi - Fm Gente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/","og_locale":"es_ES","og_type":"article","og_title":"Esc\u00e1ndalo en Punta del Este: una masajista uruguaya denunci\u00f3 fiestas sexuales ligadas al c\u00edrculo \u00edntimo de Silvio Berlusconi - Fm Gente","og_description":"Durante a\u00f1os, Punta del Este cultiv\u00f3 una imagen de refugio sofisticado del jet set internacional:","og_url":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/","og_site_name":"Fm Gente","article_published_time":"2026-05-13T13:06:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/#article","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/"},"author":{"name":"","@id":""},"headline":"Esc\u00e1ndalo en Punta del Este: una masajista uruguaya denunci\u00f3 fiestas sexuales ligadas al c\u00edrculo \u00edntimo de Silvio Berlusconi","datePublished":"2026-05-13T13:06:09+00:00","mainEntityOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/"},"wordCount":1131,"publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2026\/05\/Captura-de-pantalla-2026-05-13-a-las-08.45.07.png.webp","articleSection":["ESPECTACULO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/","url":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/","name":"Esc\u00e1ndalo en Punta del Este: una masajista uruguaya denunci\u00f3 fiestas sexuales ligadas al c\u00edrculo \u00edntimo de Silvio Berlusconi - Fm Gente","isPartOf":{"@id":"https:\/\/fmgente.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/#primaryimage"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/#primaryimage"},"thumbnailUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2026\/05\/Captura-de-pantalla-2026-05-13-a-las-08.45.07.png.webp","datePublished":"2026-05-13T13:06:09+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/escandalo-en-punta-del-este-una-masajista-uruguaya-denuncio-fiestas-sexuales-ligadas-al-circulo-intimo-de-silvio-berlusconi\/#primaryimage","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2026\/05\/Captura-de-pantalla-2026-05-13-a-las-08.45.07.png.webp","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2026\/05\/Captura-de-pantalla-2026-05-13-a-las-08.45.07.png.webp","width":658,"height":576},{"@type":"WebSite","@id":"https:\/\/fmgente.com.ar\/web\/#website","url":"https:\/\/fmgente.com.ar\/web\/","name":"Fm Gente","description":"- Jes\u00fas Mar\u00eda","publisher":{"@id":"https:\/\/fmgente.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fmgente.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fmgente.com.ar\/web\/#organization","name":"Fm Gente","url":"https:\/\/fmgente.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","contentUrl":"https:\/\/fmgente.com.ar\/web\/wp-content\/uploads\/2023\/07\/cropped-cropped-logo-sombra2.png","width":1782,"height":1782,"caption":"Fm Gente"},"image":{"@id":"https:\/\/fmgente.com.ar\/web\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/23376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/comments?post=23376"}],"version-history":[{"count":0,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/posts\/23376\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media\/23377"}],"wp:attachment":[{"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/media?parent=23376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/categories?post=23376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fmgente.com.ar\/web\/wp-json\/wp\/v2\/tags?post=23376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}